{"id":3347,"date":"2014-02-14T18:56:44","date_gmt":"2014-02-14T16:56:44","guid":{"rendered":"http:\/\/spiellandschaft.de\/kinder\/?page_id=3347"},"modified":"2014-02-14T18:56:44","modified_gmt":"2014-02-14T16:56:44","slug":"gps-tour-durch-bogenhausen","status":"publish","type":"page","link":"https:\/\/alt.spiellandschaft.de\/kinder\/kinderstadtplaene\/bogenhausen-2\/rallye-durch-bogenhausen\/gps-tour-durch-bogenhausen\/","title":{"rendered":"GPS-Tour durch Bogenhausen"},"content":{"rendered":"<p>Hast du schon mal mit einem <strong>GPS-Ger\u00e4t<\/strong> eine Schnitzeljagd gemacht? Hier findest du eine Geocaching-Tour durch Bogenhausen!<!--more--><a href=\"https:\/\/alt.spiellandschaft.de\/kinder\/wp-content\/uploads\/sites\/2\/2014\/02\/gps_kompass.jpg\"><img decoding=\"async\" class=\" wp-image-4460 alignright\" alt=\"GPS_Kompass\" src=\"https:\/\/alt.spiellandschaft.de\/kinder\/wp-content\/uploads\/sites\/2\/2014\/02\/gps_kompass.jpg\" width=\"149\" height=\"154\" \/><\/a><\/p>\n<p>Beim Geocachen geht es darum Informationen zu sammeln, die zu einem <strong>geheimen Schatz<\/strong>, dem sogenannten Final, f\u00fchren. Statt einer Schatzkarte oder Wegbeschreibung bekommst du <strong>Koordinaten<\/strong>. Wenn du diese Koordinaten in ein <strong>GPS-Ger\u00e4t<\/strong>, <strong>Smartphone<\/strong> oder <strong>Tablet<\/strong> mit GPS-Empf\u00e4nger eingibst, zeigt dir das Ger\u00e4t den Weg.<\/p>\n<p>Wir haben eine kleine <strong>digitale Schnitzeljagd<\/strong> in Bogenhausen vorbereiten. Wenn du also ein <strong>kleiner <\/strong>oder vielleicht auch schon<strong> gro\u00dfer Entdecker<\/strong> bist und einen <strong>spannenden Ausflug<\/strong> machen m\u00f6chtest, haben wir hier alle wichtigen Informationen f\u00fcr dich:<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/alt.spiellandschaft.de\/kinder\/wp-content\/uploads\/sites\/2\/2014\/02\/geocache-bogenhausen_teil1.png\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-4447\" alt=\"Geocache-Bogenhausen_Teil1\" src=\"https:\/\/alt.spiellandschaft.de\/kinder\/wp-content\/uploads\/sites\/2\/2014\/02\/geocache-bogenhausen_teil1-208x300.png\" width=\"208\" height=\"300\" srcset=\"https:\/\/alt.spiellandschaft.de\/kinder\/wp-content\/uploads\/sites\/2\/2014\/02\/geocache-bogenhausen_teil1-208x300.png 208w, https:\/\/alt.spiellandschaft.de\/kinder\/wp-content\/uploads\/sites\/2\/2014\/02\/geocache-bogenhausen_teil1.png 800w\" sizes=\"(max-width: 208px) 100vw, 208px\" \/><\/a>\u00a0<a href=\"https:\/\/alt.spiellandschaft.de\/kinder\/wp-content\/uploads\/sites\/2\/2014\/02\/geocache-bogenhausen_teil2.png\"><img decoding=\"async\" class=\"size-medium wp-image-4448 aligncenter\" alt=\"Geocache-Bogenhausen_Teil2\" src=\"https:\/\/alt.spiellandschaft.de\/kinder\/wp-content\/uploads\/sites\/2\/2014\/02\/geocache-bogenhausen_teil2-208x300.png\" width=\"208\" height=\"300\" srcset=\"https:\/\/alt.spiellandschaft.de\/kinder\/wp-content\/uploads\/sites\/2\/2014\/02\/geocache-bogenhausen_teil2-208x300.png 208w, https:\/\/alt.spiellandschaft.de\/kinder\/wp-content\/uploads\/sites\/2\/2014\/02\/geocache-bogenhausen_teil2.png 800w\" sizes=\"(max-width: 208px) 100vw, 208px\" \/><\/a><\/p>\n<p>&nbsp;<br \/>\n&nbsp;<br \/>\n&nbsp;<\/p>\n<p>Hier kannst du dir die\u00a0<a href=\"https:\/\/alt.spiellandschaft.de\/kinder\/wp-content\/uploads\/sites\/2\/2014\/02\/digitale-schnitzeljagd-durch-bogenhausen.pdf\">Digitale Schnitzeljagd durch Bogenhausen<\/a> herunterladen und <strong>ausdrucken<\/strong>.<\/p>\n<p>Falls du kein GPS-Ger\u00e4t, Smartphone oder Tablet mit GPS-Empf\u00e4nger hast, kannst du dir den <strong>Geocachekoffer<\/strong> der Spiellandschaft Stadt e.V. ausleihen. Weitere Informationen findest du <a href=\"https:\/\/alt.spiellandschaft.de\/unser-service\/verleih\/koffer\/geocachekoffer\/\">hier<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hast du schon mal mit einem GPS-Ger\u00e4t eine Schnitzeljagd gemacht? Hier findest du eine Geocaching-Tour durch Bogenhausen!<\/p>\n","protected":false},"author":4,"featured_media":0,"parent":2902,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"full-width-page.php","meta":{"_acf_changed":false,"ngg_post_thumbnail":0,"footnotes":""},"class_list":["post-3347","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/alt.spiellandschaft.de\/kinder\/wp-json\/wp\/v2\/pages\/3347","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alt.spiellandschaft.de\/kinder\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/alt.spiellandschaft.de\/kinder\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/alt.spiellandschaft.de\/kinder\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/alt.spiellandschaft.de\/kinder\/wp-json\/wp\/v2\/comments?post=3347"}],"version-history":[{"count":14,"href":"https:\/\/alt.spiellandschaft.de\/kinder\/wp-json\/wp\/v2\/pages\/3347\/revisions"}],"predecessor-version":[{"id":4462,"href":"https:\/\/alt.spiellandschaft.de\/kinder\/wp-json\/wp\/v2\/pages\/3347\/revisions\/4462"}],"up":[{"embeddable":true,"href":"https:\/\/alt.spiellandschaft.de\/kinder\/wp-json\/wp\/v2\/pages\/2902"}],"wp:attachment":[{"href":"https:\/\/alt.spiellandschaft.de\/kinder\/wp-json\/wp\/v2\/media?parent=3347"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}